{"id":723,"date":"2018-07-16T17:54:42","date_gmt":"2018-07-16T15:54:42","guid":{"rendered":"http:\/\/www.digitalbuero.at\/content\/?p=723"},"modified":"2021-07-22T02:03:30","modified_gmt":"2021-07-22T00:03:30","slug":"hey-das-bin-ja-ich-momente","status":"publish","type":"post","link":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/","title":{"rendered":"Mein Weg zu mehr &#8222;Hey, das bin ja ich!&#8220;-Momenten"},"content":{"rendered":"<p>Ein paar Monate sind jetzt nach dem\u00a0<a href=\"https:\/\/www.thespeedproject.at\" target=\"_blank\" rel=\"noopener noreferrer\">Speed Project 4.0<\/a>\u00a0ins Land gezogen und unsere Beine haben sich von den fast endlos scheinenden gemeinsam absolvierten 550 W\u00fcstenkilometern in Laufschuhen wieder halbwegs erholt. Wie dieser <a href=\"https:\/\/www.sportaktiv.com\/speed-project-wenn-10-maenner-von-la-nach-las-vegas-laufen\" target=\"_blank\" rel=\"noopener noreferrer\">&#8222;Lebens-Lauf&#8220; (\u00a9 SPORT aktiv)<\/a> bei uns bis heute nachwirkt und was man \u2013 vielleicht \u2013 daraus lernen kann, dar\u00fcber m\u00f6chte ich in diesem Beitrag kurz nachdenken.<!--more--><\/p>\n<p>Eine kurze &#8222;Speed Review&#8220; habe ich vor Kurzem dr\u00fcben im Team-Austria Blog verfasst. Jeweils die vier gleichen Fragen an alle Team-Mitglieder, mit hochinteressanten, aufschlussreichen Antworten. Einige \u00e4hnliche, aber schlie\u00dflich immer sehr pers\u00f6nliche Eindr\u00fccke kombiniert mit <em>dem<\/em> Song als Soundtrack f\u00fcr ein ganz besonderes Erlebnis namens The Speed Project.<\/p>\n<p><a href=\"https:\/\/www.thespeedproject.at\/tag\/speed-review\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lest euch unsere zehn Speed Reviews gerne durch<\/a>.<\/p>\n<h2>Das Ergebnis<\/h2>\n<p>Wie geil! Strahlende, erleichterte Gesichter unter dem &#8222;Welcome to Fabulous Las Vegas Nevada&#8220; Schild. Das Ziel ist erreicht. Ein Riesen-Abenteuer gemeinsam erlebt, aber bestimmt noch nicht ganz verdaut.<\/p>\n<figure id=\"attachment_727\" aria-describedby=\"caption-attachment-727\" style=\"width: 580px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/NTS_2018_DR_4000.jpg\" target=\"_blank\" rel=\"noopener noreferrer\" rel=\"lightbox[723]\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-727 size-large\" src=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/NTS_2018_DR_4000-1024x1024.jpg\" alt=\"TSP 2018 LA2LV \u2013\u00a0Team Austria. Foto: Gernot Eder 2018\" width=\"580\" height=\"580\" srcset=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/NTS_2018_DR_4000-1024x1024.jpg 1024w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/NTS_2018_DR_4000-150x150.jpg 150w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/NTS_2018_DR_4000-300x300.jpg 300w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/NTS_2018_DR_4000-768x768.jpg 768w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/NTS_2018_DR_4000.jpg 2048w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/a><figcaption id=\"caption-attachment-727\" class=\"wp-caption-text\">TSP 2018: Mit dem Team Austria kurz nach dem Zieleinlauf in Las Vegas<br \/>Foto: Gernot Eder 2018<\/figcaption><\/figure>\n<p>Am Ende sind es meist die tollen Bilder, Postings und Artikel, die unsere Erlebnisse beschreiben. Was man aber nicht vergessen darf: Es braucht einigen Aufwand vorher und w\u00e4hrenddessen, um erst mal so weit zu kommen. Um zum Beispiel irgendwann beim Fr\u00fchst\u00fcckskaffee ein Magazin aufzubl\u00e4ttern und sich selbst darin wiederzufinden. So wie ich mich gefreut habe, \u00fcber das im aktuellen <a href=\"https:\/\/www.sportaktiv.com\/sportaktiv-magazin-abonnieren\" target=\"_blank\" rel=\"noopener noreferrer\">SPORT aktiv Magazin<\/a> (Ausgabe Juni\/Juli 2018) abgebildete Titelfoto von mir auf der schier endlos scheinenden Death Valley Road.<\/p>\n<p>Ich verwende hier das Beispiel eines privaten Ereignisses, bin aber \u00fcberzeugt davon, dass die folgenden \u00dcberlegungen f\u00fcr alle Lebensbereiche zutreffen k\u00f6nnen (und sollen). Was braucht&#8217;s also daf\u00fcr? Einfach weiterlesen.<\/p>\n<h2>Die Arbeit<\/h2>\n<p>Machen wir uns nichts vor. Ohne Flei\u00df kein Preis. Man kann nicht kilometerweit durch die W\u00fcste laufen, ohne K\u00f6rper und Geist entsprechend darauf eingestellt zu haben. Dazu geh\u00f6rt auch fr\u00fches Aufstehen f\u00fcr das n\u00e4chste morgendliche &#8222;Date&#8220; mit dem Laufband. Oder l\u00e4ngeres Aufbleiben, um K\u00e4lte-Outfit und Stirnlampen-Set bei Dunkelheit drau\u00dfen in freier Wildbahn aufgeregt testen zu k\u00f6nnen. Hallo, Nacht-und-Nebel-Aktion \u2013 sprichw\u00f6rtlich!<\/p>\n<p>Ich finde, dass in der heutigen Zeit oft zu wenig Fokus auf die Darstellung von Arbeit, Flei\u00df und Ausdauer gelegt wird \u2013 vielmehr werden stets gesch\u00f6nte, mit Fotofiltern aufgebesserte Ergebnisse als einzige, vermeintlich im Vorbeigehen entstandene, Realit\u00e4t gezeigt. Bewusst daher hier auch ein Foto aus meinem Auto, als wir an einem verschneiten Februarmorgen am (sehr) fr\u00fchen Weg in unser <a href=\"https:\/\/maikai.at\" target=\"_blank\" rel=\"noopener noreferrer\">Fitnessstudio in Salzburg<\/a> waren.<\/p>\n<figure id=\"attachment_726\" aria-describedby=\"caption-attachment-726\" style=\"width: 580px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/Bildschirmfoto-2018-07-14-um-19.08.11.png\" target=\"_blank\" rel=\"noopener noreferrer\" rel=\"lightbox[723]\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-726 size-large\" src=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/Bildschirmfoto-2018-07-14-um-19.08.11-1024x589.png\" alt=\"Auf dem Weg ins Fitnessstudio\" width=\"580\" height=\"334\" srcset=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/Bildschirmfoto-2018-07-14-um-19.08.11-1024x589.png 1024w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/Bildschirmfoto-2018-07-14-um-19.08.11-300x173.png 300w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/Bildschirmfoto-2018-07-14-um-19.08.11-768x442.png 768w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/Bildschirmfoto-2018-07-14-um-19.08.11.png 2048w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/a><figcaption id=\"caption-attachment-726\" class=\"wp-caption-text\">Nichts geht ohne harte Arbeit und Training, das hie\u00df unter anderem auch: Um 6 Uhr 17 bei Schneefall in Salzburg ins Fitnessstudio fahren und dann ab aufs Laufband!<\/figcaption><\/figure>\n<p>Oder ein Foto vom Truck-Parkplatz in Baker, direkt hinter dem <a href=\"https:\/\/goo.gl\/maps\/shZiEzdFFDq\" target=\"_blank\" rel=\"noopener noreferrer\">The Mad Greek<\/a> Restaurant. Es zeigt &#8222;stolze&#8220; Speed Project Teilnehmer bei der bedingt glamour\u00f6sen morgendlichen Katzenw\u00e4sche. Wir haben ein g&#8217;schmackiges Gyros-Omelette hinter, und endlose Kilometer auf der Death Valley Road vor uns! Das als klares Pl\u00e4doyer f\u00fcr mehr #nofilter Wegfotos und weniger #snapseed gesch\u00f6nte Zielfotos\u2026<\/p>\n<figure id=\"attachment_734\" aria-describedby=\"caption-attachment-734\" style=\"width: 580px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/TSP_2018_Handy_unsorted-74.jpg\" target=\"_blank\" rel=\"noopener noreferrer\" rel=\"lightbox[723]\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-734 size-large\" src=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/TSP_2018_Handy_unsorted-74-1024x1024.jpg\" alt=\"The Speed Project 4.0 \u2013\u00a0Team Austria Early Birds\" width=\"580\" height=\"580\" srcset=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/TSP_2018_Handy_unsorted-74-1024x1024.jpg 1024w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/TSP_2018_Handy_unsorted-74-150x150.jpg 150w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/TSP_2018_Handy_unsorted-74-300x300.jpg 300w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/TSP_2018_Handy_unsorted-74-768x768.jpg 768w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/TSP_2018_Handy_unsorted-74.jpg 1600w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/a><figcaption id=\"caption-attachment-734\" class=\"wp-caption-text\">Der fr\u00fche Vogel w\u00e4scht sich elegant\u2026 Am Parkplatz hinterm Truck.<\/figcaption><\/figure>\n<h2>Das Ziel<\/h2>\n<p>Auch wenn es nicht immer einfach war. Ich bin \u00fcberzeugt davon, dass man ein klares Ziel vor Augen haben muss, um sich \u00fcber einen l\u00e4ngeren Zeitraum f\u00fcr eine ganz konkrete Sache zu motivieren. In meinem Fall war es tats\u00e4chlich ein kleines Polaroid vom weltber\u00fchmten &#8222;Las Vegas&#8220;-Schild, gleichzeitig das Ziel unseres Laufabenteuers, das ich bei den Trainingseinheiten bei mir und teilweise auch am Display des Laufbands direkt vor Augen hatte. Und das bringt mich zum n\u00e4chsten wichtigen Punkt.<\/p>\n<h2>Die Vision<\/h2>\n<p>Last but not least \u2013 vielmehr ganz am Beginn eines jeden Vorhabens braucht&#8217;s eine klare Vision. Eine solche hatte ich schon bei meinem <a href=\"http:\/\/www.digitalbuero.at\/content\/2016\/09\/01\/2-sterne-bewertung-bei-amazon\/\">Buch<\/a>, aber auch bei einigen anderen gr\u00f6\u00dferen Vorhaben in meinem Leben gebraucht, um mich dazwischen immer wieder zu motivieren und Schritt f\u00fcr Schritt meinem Ziel n\u00e4herzubringen.<\/p>\n<blockquote><p>Wer keine Vision hat, wird auch nie ein Ziel erreichen, sondern sich stets mit Durchwurschteln zufriedengeben. Dazu sollten uns unsere eigene Zukunft und die unserer Kinder zu wertvoll sein. \u2013\u00a0<em>Dirk M\u00fcller, &#8222;Mister DAX\u201c, B\u00f6rsenmakler &amp; Buchautor<\/em><\/p><\/blockquote>\n<div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"youtube-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LnlvdXR1YmUtbm9jb29raWUuY29tL2VtYmVkL2RNcWRHSnJTbnN3P3JlbD0wJmFtcDtzdGFydD03NiIgd2lkdGg9IjU2MCIgaGVpZ2h0PSIzMTUiIGZyYW1lYm9yZGVyPSIwIiBhbGxvd2Z1bGxzY3JlZW49ImFsbG93ZnVsbHNjcmVlbiI+Jmx0O3NwYW4gZGF0YS1tY2UtdHlwZT0iYm9va21hcmsiIHN0eWxlPSJkaXNwbGF5OiBpbmxpbmUtYmxvY2s7IHdpZHRoOiAwcHg7IG92ZXJmbG93OiBoaWRkZW47IGxpbmUtaGVpZ2h0OiAwOyIgY2xhc3M9Im1jZV9TRUxSRVNfc3RhcnQiJmd0O++7vyZsdDsvc3BhbiZndDs8L2lmcmFtZT4=\">\n<div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-youtube\">\n<div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/borlabs-cookie\/1\/yt_dMqdGJrSnsw_hqdefault.jpg')\"><\/div>\n<div class=\"brlbs-cmpnt-cb-main\">\n<div class=\"brlbs-cmpnt-cb-play-button\"><\/div>\n<div class=\"brlbs-cmpnt-cb-content\">\n<p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>YouTube<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p>\n<p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div>\n<div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p>Daf\u00fcr m\u00f6chte ich &#8222;Mister DAX&#8220; <a href=\"https:\/\/amzn.to\/2uCd8kq\" target=\"_blank\" rel=\"noopener noreferrer\">Dirk M\u00fcller aus einem seiner B\u00fccher<\/a> zitieren. Beim Lesen habe ich mir die folgende Stelle nicht nur sofort markiert, sondern auch kurz danach ausgedruckt und im B\u00fcro aufgeh\u00e4ngt:<\/p>\n<p><em>&#8222;Es hei\u00dft, dass der erfolgreiche Rennfahrer das Rennen nur deshalb gewinnen kann, weil er sich schon vor dem Start vorstellt, wie er durchs Ziel f\u00e4hrt und den Siegerkranz entgegennimmt.<br \/>\n<\/em><em>Die Vision ist der st\u00e4rkste Antrieb und das wichtigste Element f\u00fcr den Erfolg.<br \/>\n<\/em><em>Und bei aller Wertsch\u00e4tzung, es war der uns\u00e4glichste Satz, den Helmut Schmidt jemals gesagt hat: &#8218;Wer Visionen hat, der soll zum Arzt gehen.&#8216;<br \/>\n<\/em><em>Richtig ist: Wer keine Vision hat, wird auch nie ein Ziel erreichen, sondern sich stets mit Durchwurschteln zufriedengeben. Dazu sollten uns unsere eigene Zukunft und die unserer Kinder zu wertvoll sein.&#8220;<\/em><\/p>\n<p><em>\u2013 Dirk M\u00fcller, \u201eMister DAX\u201c, B\u00f6rsenmakler &amp; Buchautor<\/em><\/p>\n<h2>Das Fazit<\/h2>\n<p>Was nehmen wir am Ende von dieser Geschichte mit? <strong>Ich lerne daraus: &#8222;Von nix kummt nix&#8220; ist schlie\u00dflich nur eine Abk\u00fcrzung daf\u00fcr, dass aus Tr\u00e4umen W\u00fcnsche, aus W\u00fcnschen Ziele, aus Zielen Erlebnisse und aus Erlebnissen bleibende Eindr\u00fccke und Erinnerungen werden k\u00f6nnen.<\/strong> Vorausgesetzt man bringt auch genug Fokus, Elan und Ausdauer auf, dran zu bleiben.<\/p>\n<p>Ich habe es mir mittlerweile zur Gewohnheit gemacht, Bilder und Texte die mich inspirieren nicht nur digital abzuspeichern sondern auch auszudrucken und an stark frequentierten Pl\u00e4tzen in meinem Lebensbereich zu platzieren. Damit aus der n\u00e4chsten Vision bald wieder Realit\u00e4t entstehen kann. Damit ich beim Blick in ein Magazin auch zuk\u00fcnftig bald wieder statt einem &#8222;Hey, das m\u00f6chte ich auch irgendwann mal\u2026&#8220;-Gedanken die n\u00e4chste &#8222;Hey, das bin ja ich!&#8220;-Freude empfinden kann.<\/p>\n<figure id=\"attachment_735\" aria-describedby=\"caption-attachment-735\" style=\"width: 580px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/TSP_2018_DR_3587.jpg\" target=\"_blank\" rel=\"noopener noreferrer\" rel=\"lightbox[723]\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-735 size-large\" src=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/TSP_2018_DR_3587-1024x683.jpg\" alt=\"TSP 2018 LA2LV \u2013\u00a0Team Austria. Thomas Sommeregger. Foto: Gernot Eder 2018\" width=\"580\" height=\"387\" srcset=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/TSP_2018_DR_3587-1024x683.jpg 1024w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/TSP_2018_DR_3587-300x200.jpg 300w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/TSP_2018_DR_3587-768x512.jpg 768w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/TSP_2018_DR_3587.jpg 1600w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/a><figcaption id=\"caption-attachment-735\" class=\"wp-caption-text\">Der &#8222;Hey, das bin ja ich!&#8220;-Moment 2018: In Laufschuhen auf der endlos langen Geraden in Richtung Death Valley\u2026 Foto: Gernot Eder 2018<\/figcaption><\/figure>\n<p>Welche Vision(en) tragt ihr mit euch herum? Welche Bilder und Gedanken die euch \u2013 privat wie beruflich \u2013 antreiben findet man bei euch so im Kopf, am Smartphone, oder am K\u00fchlschrank?<\/p>\n<p>Take care,<br \/>\nThomas<\/p>\n<p>PS: H\u00f6rt gerne in unseren ganz pers\u00f6nlichen <a href=\"https:\/\/www.thespeedproject.at\/2018\/07\/16\/unser-soundtrack-zum-speed-project\/\" target=\"_blank\" rel=\"noopener noreferrer\">&#8222;<strong>The Speed Project&#8220;-Soundtrack<\/strong><\/a> bei Spotify rein, w\u00e4hrend ihr euch dar\u00fcber Gedanken macht oder vielleicht diesen Artikel noch einmal von vorne durchlest.<\/p>\n<div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vb3Blbi5zcG90aWZ5LmNvbS9lbWJlZC91c2VyL3NvbW1hMTk3Ny9wbGF5bGlzdC80aFZYaVR5NktTNmFVYWNLOHY1em5BIiB3aWR0aD0iMzAwIiBoZWlnaHQ9IjM4MCIgZnJhbWVib3JkZXI9IjAiPjwvaWZyYW1lPg==\">\n<div class=\"brlbs-cmpnt-cb-preset-a\">\n<p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Standard<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p>\n<div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div>\n<p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ein paar Monate sind jetzt nach dem\u00a0Speed Project 4.0\u00a0ins Land gezogen und unsere Beine haben sich von den fast endlos scheinenden gemeinsam absolvierten 550 W\u00fcstenkilometern in Laufschuhen wieder halbwegs erholt. Wie dieser &#8222;Lebens-Lauf&#8220; (\u00a9 SPORT aktiv) bei uns bis heute nachwirkt und was man \u2013 vielleicht \u2013 daraus lernen kann, dar\u00fcber m\u00f6chte ich in diesem [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":724,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[225,293],"tags":[319,316,337,336,338,339,340],"class_list":["post-723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktivitaten","category-sport","tag-laufen","tag-running","tag-team-austria","tag-the-speed-project","tag-vision","tag-ziel","tag-ziele"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mein Weg zu mehr &quot;Hey, das bin ja ich!&quot;-Momenten - Thomas&#039; Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mein Weg zu mehr &quot;Hey, das bin ja ich!&quot;-Momenten - Thomas&#039; Blog\" \/>\n<meta property=\"og:description\" content=\"Ein paar Monate sind jetzt nach dem\u00a0Speed Project 4.0\u00a0ins Land gezogen und unsere Beine haben sich von den fast endlos scheinenden gemeinsam absolvierten 550 W\u00fcstenkilometern in Laufschuhen wieder halbwegs erholt. Wie dieser &#8222;Lebens-Lauf&#8220; (\u00a9 SPORT aktiv) bei uns bis heute nachwirkt und was man \u2013 vielleicht \u2013 daraus lernen kann, dar\u00fcber m\u00f6chte ich in diesem [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/\" \/>\n<meta property=\"og:site_name\" content=\"Thomas&#039; Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/thomas.sommeregger\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/digitalbuero.at\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-16T15:54:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-22T00:03:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/DSC0261.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1356\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thomas Sommeregger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tsommeregger\" \/>\n<meta name=\"twitter:site\" content=\"@tsommeregger\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Sommeregger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2018\\\/07\\\/16\\\/hey-das-bin-ja-ich-momente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2018\\\/07\\\/16\\\/hey-das-bin-ja-ich-momente\\\/\"},\"author\":{\"name\":\"Thomas Sommeregger\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#\\\/schema\\\/person\\\/7d7adc47b52b6c92021d3a5bce99592e\"},\"headline\":\"Mein Weg zu mehr &#8222;Hey, das bin ja ich!&#8220;-Momenten\",\"datePublished\":\"2018-07-16T15:54:42+00:00\",\"dateModified\":\"2021-07-22T00:03:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2018\\\/07\\\/16\\\/hey-das-bin-ja-ich-momente\\\/\"},\"wordCount\":1128,\"commentCount\":8,\"image\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2018\\\/07\\\/16\\\/hey-das-bin-ja-ich-momente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/DSC0261.jpg\",\"keywords\":[\"laufen\",\"running\",\"team austria\",\"the speed project\",\"vision\",\"ziel\",\"ziele\"],\"articleSection\":[\"Aktivit\u00e4ten\",\"Sport\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2018\\\/07\\\/16\\\/hey-das-bin-ja-ich-momente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2018\\\/07\\\/16\\\/hey-das-bin-ja-ich-momente\\\/\",\"url\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2018\\\/07\\\/16\\\/hey-das-bin-ja-ich-momente\\\/\",\"name\":\"Mein Weg zu mehr \\\"Hey, das bin ja ich!\\\"-Momenten - Thomas&#039; Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2018\\\/07\\\/16\\\/hey-das-bin-ja-ich-momente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2018\\\/07\\\/16\\\/hey-das-bin-ja-ich-momente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/DSC0261.jpg\",\"datePublished\":\"2018-07-16T15:54:42+00:00\",\"dateModified\":\"2021-07-22T00:03:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#\\\/schema\\\/person\\\/7d7adc47b52b6c92021d3a5bce99592e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2018\\\/07\\\/16\\\/hey-das-bin-ja-ich-momente\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2018\\\/07\\\/16\\\/hey-das-bin-ja-ich-momente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2018\\\/07\\\/16\\\/hey-das-bin-ja-ich-momente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/DSC0261.jpg\",\"contentUrl\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/DSC0261.jpg\",\"width\":2048,\"height\":1356,\"caption\":\"The Speed Project - SPORT Aktiv Magazin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2018\\\/07\\\/16\\\/hey-das-bin-ja-ich-momente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktivit\u00e4ten\",\"item\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/category\\\/aktivitaten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mein Weg zu mehr &#8222;Hey, das bin ja ich!&#8220;-Momenten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/\",\"name\":\"Thomas&#039; Blog\",\"description\":\"Meine Gedanken verpackt in Null und Eins, 100% pers\u00f6nlich\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#\\\/schema\\\/person\\\/7d7adc47b52b6c92021d3a5bce99592e\",\"name\":\"Thomas Sommeregger\",\"description\":\"Hallo, mein Name ist Thomas Sommeregger. Ich bin Betreiber sowie Haupt-Autor von Thomas' Blog. Meine Gedanken drehen sich hier recht breit um das Arbeits-, Familien- und Freizeitleben. Als Patchwork-Vater, Unternehmer und Hobby-Marathonl\u00e4ufer lebe ich in der Stadt Salzburg in \u00d6sterreich. Wenn dich Online Marketing, Unternehmertum, (Lauf-)Sport oder hin und wieder die eine oder andere Anekdote von mir interessieren, freue ich mich, wenn du mir weiter folgst.\",\"sameAs\":[\"https:\\\/\\\/www.digitalbuero.at\",\"https:\\\/\\\/www.facebook.com\\\/digitalbuero.at\",\"https:\\\/\\\/twitter.com\\\/tsommeregger\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thomassommeregger\",\"https:\\\/\\\/x.com\\\/tsommeregger\",\"https:\\\/\\\/soundcloud.com\\\/user-649426735\"],\"url\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/author\\\/thomas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mein Weg zu mehr \"Hey, das bin ja ich!\"-Momenten - Thomas&#039; Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/","og_locale":"de_DE","og_type":"article","og_title":"Mein Weg zu mehr \"Hey, das bin ja ich!\"-Momenten - Thomas&#039; Blog","og_description":"Ein paar Monate sind jetzt nach dem\u00a0Speed Project 4.0\u00a0ins Land gezogen und unsere Beine haben sich von den fast endlos scheinenden gemeinsam absolvierten 550 W\u00fcstenkilometern in Laufschuhen wieder halbwegs erholt. Wie dieser &#8222;Lebens-Lauf&#8220; (\u00a9 SPORT aktiv) bei uns bis heute nachwirkt und was man \u2013 vielleicht \u2013 daraus lernen kann, dar\u00fcber m\u00f6chte ich in diesem [&hellip;]","og_url":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/","og_site_name":"Thomas&#039; Blog","article_publisher":"https:\/\/www.facebook.com\/thomas.sommeregger","article_author":"https:\/\/www.facebook.com\/digitalbuero.at","article_published_time":"2018-07-16T15:54:42+00:00","article_modified_time":"2021-07-22T00:03:30+00:00","og_image":[{"width":2048,"height":1356,"url":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/DSC0261.jpg","type":"image\/jpeg"}],"author":"Thomas Sommeregger","twitter_card":"summary_large_image","twitter_creator":"@tsommeregger","twitter_site":"@tsommeregger","twitter_misc":{"Verfasst von":"Thomas Sommeregger","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/#article","isPartOf":{"@id":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/"},"author":{"name":"Thomas Sommeregger","@id":"https:\/\/www.digitalbuero.at\/content\/#\/schema\/person\/7d7adc47b52b6c92021d3a5bce99592e"},"headline":"Mein Weg zu mehr &#8222;Hey, das bin ja ich!&#8220;-Momenten","datePublished":"2018-07-16T15:54:42+00:00","dateModified":"2021-07-22T00:03:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/"},"wordCount":1128,"commentCount":8,"image":{"@id":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/DSC0261.jpg","keywords":["laufen","running","team austria","the speed project","vision","ziel","ziele"],"articleSection":["Aktivit\u00e4ten","Sport"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/","url":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/","name":"Mein Weg zu mehr \"Hey, das bin ja ich!\"-Momenten - Thomas&#039; Blog","isPartOf":{"@id":"https:\/\/www.digitalbuero.at\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/#primaryimage"},"image":{"@id":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/DSC0261.jpg","datePublished":"2018-07-16T15:54:42+00:00","dateModified":"2021-07-22T00:03:30+00:00","author":{"@id":"https:\/\/www.digitalbuero.at\/content\/#\/schema\/person\/7d7adc47b52b6c92021d3a5bce99592e"},"breadcrumb":{"@id":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/#primaryimage","url":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/DSC0261.jpg","contentUrl":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2018\/07\/DSC0261.jpg","width":2048,"height":1356,"caption":"The Speed Project - SPORT Aktiv Magazin"},{"@type":"BreadcrumbList","@id":"https:\/\/www.digitalbuero.at\/content\/2018\/07\/16\/hey-das-bin-ja-ich-momente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.digitalbuero.at\/content\/"},{"@type":"ListItem","position":2,"name":"Aktivit\u00e4ten","item":"https:\/\/www.digitalbuero.at\/content\/category\/aktivitaten\/"},{"@type":"ListItem","position":3,"name":"Mein Weg zu mehr &#8222;Hey, das bin ja ich!&#8220;-Momenten"}]},{"@type":"WebSite","@id":"https:\/\/www.digitalbuero.at\/content\/#website","url":"https:\/\/www.digitalbuero.at\/content\/","name":"Thomas&#039; Blog","description":"Meine Gedanken verpackt in Null und Eins, 100% pers\u00f6nlich","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.digitalbuero.at\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.digitalbuero.at\/content\/#\/schema\/person\/7d7adc47b52b6c92021d3a5bce99592e","name":"Thomas Sommeregger","description":"Hallo, mein Name ist Thomas Sommeregger. Ich bin Betreiber sowie Haupt-Autor von Thomas' Blog. Meine Gedanken drehen sich hier recht breit um das Arbeits-, Familien- und Freizeitleben. Als Patchwork-Vater, Unternehmer und Hobby-Marathonl\u00e4ufer lebe ich in der Stadt Salzburg in \u00d6sterreich. Wenn dich Online Marketing, Unternehmertum, (Lauf-)Sport oder hin und wieder die eine oder andere Anekdote von mir interessieren, freue ich mich, wenn du mir weiter folgst.","sameAs":["https:\/\/www.digitalbuero.at","https:\/\/www.facebook.com\/digitalbuero.at","https:\/\/twitter.com\/tsommeregger","https:\/\/www.linkedin.com\/in\/thomassommeregger","https:\/\/x.com\/tsommeregger","https:\/\/soundcloud.com\/user-649426735"],"url":"https:\/\/www.digitalbuero.at\/content\/author\/thomas\/"}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/posts\/723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/comments?post=723"}],"version-history":[{"count":0,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/posts\/723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/media\/724"}],"wp:attachment":[{"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/media?parent=723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/categories?post=723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/tags?post=723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}