{"id":1869,"date":"2021-01-07T09:00:00","date_gmt":"2021-01-07T08:00:00","guid":{"rendered":"https:\/\/www.digitalbuero.at\/content\/?p=1869"},"modified":"2021-01-05T18:21:04","modified_gmt":"2021-01-05T17:21:04","slug":"du-brauchst-nix-wissen","status":"publish","type":"post","link":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/","title":{"rendered":"Du brauchst nix wissen\u2026"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Welche <strong>weisen Worte<\/strong> mir mein HTL-Professor und Klassenvorstand vor fast 30 Jahren mitgegeben hat und warum diese heute f\u00fcr mich<strong> in Sachen Aus- und Weiterbildung <\/strong>aktueller denn je sind, das liest du gleich in meinem neuen Artikel.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"has-background-color has-secondary-background-color has-text-color has-background\">Das ganze Wissen der Welt ist heute oft nur einen Klick, einen Wisch oder eine Suchanfrage entfernt. Vieles davon noch dazu kostenlos. Warum wir dennoch nicht aufh\u00f6ren d\u00fcrfen zu lernen und wie man heute besser und <em>anders<\/em> lernt? Dar\u00fcber habe ich mir auf Basis eines Uralt-Zitates meines HTL-Professors ein paar Gedanken gemacht. <\/p>\n\n\n\n<p>Ich glaube es war nur ein schneller Nebensatz, der in einer Unterrichtsstunde gefallen ist. Ungef\u00e4hr dritte, vierte Klasse HTL, ich als Teenager, jedenfalls vor dem Jahr 1995. Ganz bestimmt jedoch in der<strong> &#8222;Pr\u00e4-Google&#8220;-\u00c4ra<\/strong>, denn ich erinnere mich, nur im Werkst\u00e4ttenlabor \u2013\u00a0ganz hinten im Eck \u2013 gab es eine PC-Workstation, die mit dem damals neuen, magischen Ding namens &#8222;Internet&#8220; verbunden werden konnte.<\/p>\n\n\n\n<p>Wir sprechen von einem fr\u00fchen Netscape-Navigator (oder vielleicht sogar noch dem Mosaic-Browser) als <strong>Eingangstor zum &#8222;World Wide Web&#8220;<\/strong>, beschr\u00e4nkter Nutzungszeit bei minimaler Bandbreite und einem Elektronik- und Nachrichtentechnik-Diplomingenieur in seinen Mittvierzigern, der den wohl den Gro\u00dfteil seines Wissens noch aus Ordnern, Sammelmappen und B\u00fcchern bezogen hat. <\/p>\n\n\n\n<p>Und dennoch fiel irgendwann <strong>der folgende Satz<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Du brauchst nix wissen, du musst nur wissen, wo&#8217;s steht.<\/p><cite>Mein HTL-Professor, ca. 1993<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Wow! Das ist aus heutiger Sicht gar nicht mal so falsch, oder? Denn jegliches Hintergrund- und Detailwissen haben Sch\u00fcler ab ihrem (erfahrungsgem\u00e4\u00df sp\u00e4testens) zehnten Lebensjahr in Form eines <strong>Smartphones in ihren Schul-, Hand- oder Hosentaschen<\/strong>. <\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Du willst keine Updates mehr verpassen? Trage einfach deine E-Mail Adresse ein und erhalte k\u00fcnftig bei jedem neuen Artikel automatisch eine Nachricht.<\/p>\n\n\n<div class=\"emaillist\" id=\"es_form_f2-n1\"><form action=\"\/content\/wp-json\/wp\/v2\/posts\/1869#es_form_f2-n1\" method=\"post\" class=\"es_subscription_form es_shortcode_form  es_ajax_subscription_form\" id=\"es_subscription_form_6a58192298cd0\" data-source=\"ig-es\" data-form-id=\"2\"><div class=\"es-field-wrap\"><label>Name<br \/><input type=\"text\" name=\"esfpx_name\" class=\"ig_es_form_field_name\" placeholder=\"Dein Name (nur wenn du m\u00f6chtest)\" value=\"\" \/><\/label><\/div><div class=\"es-field-wrap ig-es-form-field\"><label class=\"es-field-label\">E-Mail*<br \/><input class=\"es_required_field es_txt_email ig_es_form_field_email ig-es-form-input\" type=\"email\" name=\"esfpx_email\" value=\"\" placeholder=\"Deine E-Mail Adresse\" required=\"required\" \/><\/label><\/div><input type=\"hidden\" name=\"esfpx_lists[]\" value=\"ae939cc0ab49\" \/><input type=\"hidden\" name=\"esfpx_form_id\" value=\"2\" \/><input type=\"hidden\" name=\"es\" value=\"subscribe\" \/>\n\t\t\t<input type=\"hidden\" name=\"esfpx_es_form_identifier\" value=\"f2-n1\" \/>\n\t\t\t<input type=\"hidden\" name=\"esfpx_es_email_page\" value=\"1869\" \/>\n\t\t\t<input type=\"hidden\" name=\"esfpx_es_email_page_url\" value=\"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/\" \/>\n\t\t\t<input type=\"hidden\" name=\"esfpx_status\" value=\"Unconfirmed\" \/>\n\t\t\t<input type=\"hidden\" name=\"esfpx_es-subscribe\" id=\"es-subscribe-6a58192298cd0\" value=\"446c204d77\" \/>\n\t\t\t<label style=\"position:absolute;top:-99999px;left:-99999px;z-index:-99;\" aria-hidden=\"true\"><span hidden>Bitte lasse dieses Feld leer.<\/span><input type=\"email\" name=\"esfpx_es_hp_email\" class=\"es_required_field\" tabindex=\"-1\" autocomplete=\"-1\" value=\"\" \/><\/label><label style=\"display: inline\"><input type=\"checkbox\" name=\"es_gdpr_consent\" value=\"true\" required=\"required\" \/>&nbsp;Ja, ich m\u00f6chte eine automatische E-Mail Nachricht zu jedem neu ver\u00f6ffentlichten Beitrag erhalten! (Sicheres \"Double Opt-In\", Abmeldung jederzeit m\u00f6glich)<\/label><br \/><input type=\"submit\" name=\"submit\" class=\"es_subscription_form_submit es_submit_button es_textbox_button\" id=\"es_subscription_form_submit_6a58192298cd0\" value=\"Anmelden\" \/><span class=\"es_spinner_image\" id=\"spinner-image\"><img decoding=\"async\" src=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/plugins\/email-subscribers\/lite\/public\/images\/spinner.gif\" alt=\"Loading\" \/><\/span><\/form><span class=\"es_subscription_message \" id=\"es_subscription_message_6a58192298cd0\" role=\"alert\" aria-live=\"assertive\"><\/span><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Wie funktioniert ein <a href=\"https:\/\/www.youtube.com\/watch?v=6kJuuPxo4Q0\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Elektromotor<\/a>? Was sagt uns <a href=\"https:\/\/www.youtube.com\/watch?v=FECtVbC-mgk\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">der pythagor\u00e4ische Lehrsatz<\/a>? Und wie war das noch mal mit dem Ungl\u00fcck der <a href=\"https:\/\/de.wikipedia.org\/wiki\/LZ_129\" target=\"_blank\" rel=\"noreferrer noopener\">Hindenburg<\/a>? Alles <strong>Dinge, die man innerhalb weniger Klicks herausfinden kann<\/strong> \u2013\u00a0Google, Wikipedia, YouTube und Co. sei Dank, und binnen wenigen (aufmerksamen!) Minuten ist man schlauer!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Was Sch\u00fcler lernen m\u00fcss(t)en<\/h2>\n\n\n\n<p>Ich bin der Ansicht, dass jeder Lehrer \u2013\u00a0ganz egal ob in der Volksschule, der Oberstufe oder im MBA-Lehrgang \u2013 seinen Sch\u00fclern im Jahr 2021 &#8222;nur mehr&#8220;<strong> die folgenden drei Dinge<\/strong> beibringen muss: <\/p>\n\n\n\n<ol class=\"wp-block-list\"><li><a href=\"#eins\">Interesse und Neugierde<\/a><\/li><li><a href=\"#zwei\">Quellen und Werkzeuge<\/a><\/li><li><a href=\"#drei\">Hausverstand und Beharrlichkeit<\/a><\/li><\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"eins\">1. Interesse und Neugierde<\/h3>\n\n\n\n<p>Lasst uns die unaufh\u00f6rliche Motivation vermitteln, etwas Neues lernen, wissen, herausfinden zu wollen. <strong>Unaufh\u00f6rlich<\/strong> im wahrsten Sinne des Wortes, dass das Lernen weder am Nachmittag, noch in den Ferien, noch &#8222;sp\u00e4ter&#8220; im Leben \u2013&nbsp; nach einem Schul-, Lehr- oder Studienabschluss \u2013&nbsp;zu Ende sein wird. <\/p>\n\n\n\n<p>Die Dynamik der globalen Entwicklungen wird es gar nicht zulassen, unsere <strong>Gier auf Neues<\/strong> abzulegen. Zumindest nicht zu lange, wenn man in gesundheitlichen, wirtschaftlichen und sozialen Belangen nicht nur am Ball bleiben, sondern ganz vorne mitmischen m\u00f6chte. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"zwei\">2. Quellen und Werkzeuge<\/h3>\n\n\n\n<p>Lasst uns Freude machen auf moderne Tools und effiziente Prozesse. Freude auf alles rund um das gar nicht mal so einfache Handwerk des <strong>smarten Recherchierens<\/strong>. Wer ist schneller, wer hat neuere, fundiertere Quellen? Wer stellt dabei die richtigen Fragen an das jeweils beste Tool? All das zu beherrschen wird k\u00fcnftig einen Wettbewerbsvorteil ausmachen.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Wie oft nutzt du das <em>Smart<\/em> in deinem <em>Phone<\/em> wirklich? <\/p><cite>Thomas&#8216; (Selbst-)Kritik Anfang 2021<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Wir brauchen laut meinem HTL-Professor schlie\u00dflich (fast) nichts zu wissen, aber es ist alles andere als selbstverst\u00e4ndlich, dass sich sowohl Kinder als auch Erwachsene <strong>das <em>Smart<\/em> in ihrem <em>Phone<\/em><\/strong> wirklich zu Eigen machen. Ganz egal wie die verwendeten <a href=\"https:\/\/www.google.at\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Findmaschinen<\/a> des neuen Jahrzehnts schlie\u00dflich hei\u00dfen werden, ein beliebig gro\u00dfer, 24\/7 mit dem Internet verbundener Touchscreen wird wohl auch in naher Zukunft die Vermittlerrolle zwischen uns Menschen und allem Wissen dieser Welt einnehmen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"drei\">3. Hausverstand und Beharrlichkeit<\/h3>\n\n\n\n<p>Und last but not least: Lasst uns einen Mix aus &#8222;logischem&#8220;, hinterfragendem und selbst\u00e4ndigem <strong>Mit- und Nachdenken<\/strong> f\u00f6rdern \u2013\u00a0bei allem was man tut. Der gute alte &#8222;Hausverstand&#8220; also wieder, Common Sense auf Englisch. Gepaart mit dem &#8222;Biss&#8220;, so lange an etwas dran zu bleiben, bis man schlie\u00dflich etwas gelernt und\/oder herausgefunden hat.<\/p>\n\n\n\n<p>Idealerweise geschieht das alles nicht ausschlie\u00dflich alleine, ganz im Gegenteil, <strong>im regen Austausch<\/strong> mit seinen Mitmenschen \u2013\u00a0 Mitsch\u00fclern, Eltern und Familie, Lehrern oder anderen Vorbildern. Ganz egal ,ob diese mit einem im selben Raum oder tausende Kilometer entfernt sind, die Technik macht&#8217;s m\u00f6glich, nimmt einem aber nicht den aktiven ersten Schritt der Kontaktaufnahme, des Nachfragens, des um Hilfe Bittens ab. <\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Alles Wissen und alle Vermehrung unseres Wissens endet nicht mit einem Schlusspunkt, sondern mit Fragezeichen.<\/p><cite>Hermann Hesse<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Ich kenne es selbst, <a href=\"https:\/\/www.digitalbuero.at\/content\/2020\/10\/04\/das-kann-ich-nicht\/\">etwas Neues zu lernen<\/a> braucht oft nur wenige Minuten. Dennoch nimmt man sich nicht die Zeit und\/oder die M\u00fche auf sich, diverse Ablenkungen mal beiseite zu legen, um etwas <strong>wirklich konzentriert <\/strong>zu lesen, zu verstehen, zu lernen. Hast du dich nicht auch schon einmal dabei erwischt, (halb-)stundenlang in endlosen Social Media Feeds zu scrollen, mit immer neuen Eindr\u00fccken im Sekundenrhythmus, w\u00e4hrend dir das aufmerksame Anschauen eines siebenmin\u00fctigen Videos &#8222;ewig&#8220; lange vorkommt?<\/p>\n\n\n\n<p>Ich hoffe stark, dass wir und vor allem unsere Kinder es durch <a href=\"https:\/\/www.digitalbuero.at\/content\/2020\/10\/18\/reden-wir-ueber-tiktok-tabea\/\">TikTok und Co.<\/a> nicht vollst\u00e4ndig verlernen, uns <strong>l\u00e4nger als ein paar Sekunden <\/strong>auf eine Sache konzentrieren zu k\u00f6nnen, vielmehr konzentrieren zu <em>wollen<\/em>! <\/p>\n\n\n\n<p class=\"has-background-color has-accent-background-color has-text-color has-background\"><strong>Lernen von gestern<\/strong> = Auswendiglernen von statischen Informationen, ohne Kontext und kritischem Hinterfragen.<br><strong>Lernen f\u00fcr morgen<\/strong> =<strong> <\/strong>Neugieriges und proaktives Recherchieren mit modernen Hilfsmitteln, ohne Scheu vor Fehlschl\u00e4gen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Du brauchst nix wissen, du musst nur wissen, wo&#8217;s steht<\/h2>\n\n\n\n<p>Wie siehst du das? Habe ich etwas Wichtiges vergessen oder sehe ich diese Punkte komplett falsch? Schreib mir gerne eine Antwort in den Kommentaren!<\/p>\n\n\n\n<p>Ich w\u00fcnsche dir jedenfalls<strong> einen guten Start<\/strong> ins Jahr 2021, das hoffentlich auch f\u00fcr Dich gesund, gl\u00fccklich und aufs Neue lehrreich verl\u00e4uft!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/signature-thomas.png\" rel=\"lightbox[1869]\"><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"100\" src=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/signature-thomas.png\" alt=\"Signature Thomas\" class=\"wp-image-1138\"\/><\/a><\/figure>\n\n\n\n<p>PS: Ein gro\u00dfes <strong>Danke<\/strong> gilt meinem Sohn Gabriel! Du hast mich beim gemeinsamen Lernen in den letzten Wochen an meine Schulzeit erinnert und mich dabei f\u00fcr diesen Beitrag inspiriert.<\/p>\n\n\n\n<p>PPS: Danke auch f\u00fcr diesen aktuellen Artikel einer Lehrerin bei DerStandard.at: <a href=\"https:\/\/www.derstandard.at\/story\/2000122632137\/warum-corona-das-schulsystem-an-die-wand-faehrt\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.derstandard.at\/story\/2000122632137\/warum-corona-das-schulsystem-an-die-wand-faehrt<\/a>. \u201eJa, es gibt einen tats\u00e4chlichen Zusammenhang zwischen \u201aeinem Kind etwas zutrauen\u2018 und dem, was sich ein Kind zutraut.\u201c Trauen wir doch unseren Kindern und Sch\u00fclern zu, mit all den Ver\u00e4nderungen und aktuellen M\u00f6glichkeiten in der Wissensvermittlung verantwortungsbewusst und zeitgem\u00e4\u00df\b umzugehen!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Welche weisen Worte mir mein HTL-Professor und Klassenvorstand vor fast 30 Jahren mitgegeben hat und warum diese heute f\u00fcr mich in Sachen Aus- und Weiterbildung aktueller denn je sind, das liest du gleich in meinem neuen Artikel.<\/p>\n","protected":false},"author":2,"featured_media":1881,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[391,409],"tags":[440,387,410,392,439],"class_list":["post-1869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learning","category-life","tag-bildung","tag-learning","tag-life","tag-lifelonglearning","tag-schule"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Du brauchst nix wissen\u2026 - Was Sch\u00fcler lernen m\u00fcss(t)en - Thomas&#039; Blog<\/title>\n<meta name=\"description\" content=\"\u2026\u00a0du musst nur wissen, wo&#039;s steht. Was mir mein HTL-Professor beigebracht hat und warum einer seiner Spr\u00fcche heute mehr gilt denn je.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Du brauchst nix wissen\u2026 - Was Sch\u00fcler lernen m\u00fcss(t)en - Thomas&#039; Blog\" \/>\n<meta property=\"og:description\" content=\"\u2026\u00a0du musst nur wissen, wo&#039;s steht. Was mir mein HTL-Professor beigebracht hat und warum einer seiner Spr\u00fcche heute mehr gilt denn je.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/\" \/>\n<meta property=\"og:site_name\" content=\"Thomas&#039; Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/thomas.sommeregger\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/digitalbuero.at\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-07T08:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2021\/01\/thomas-2021-a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thomas Sommeregger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tsommeregger\" \/>\n<meta name=\"twitter:site\" content=\"@tsommeregger\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Sommeregger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2021\\\/01\\\/07\\\/du-brauchst-nix-wissen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2021\\\/01\\\/07\\\/du-brauchst-nix-wissen\\\/\"},\"author\":{\"name\":\"Thomas Sommeregger\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#\\\/schema\\\/person\\\/7d7adc47b52b6c92021d3a5bce99592e\"},\"headline\":\"Du brauchst nix wissen\u2026\",\"datePublished\":\"2021-01-07T08:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2021\\\/01\\\/07\\\/du-brauchst-nix-wissen\\\/\"},\"wordCount\":1060,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2021\\\/01\\\/07\\\/du-brauchst-nix-wissen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/thomas-2021-a.jpg\",\"keywords\":[\"bildung\",\"learning\",\"life\",\"lifelonglearning\",\"Schule\"],\"articleSection\":[\"Learning\",\"Life\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2021\\\/01\\\/07\\\/du-brauchst-nix-wissen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2021\\\/01\\\/07\\\/du-brauchst-nix-wissen\\\/\",\"url\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2021\\\/01\\\/07\\\/du-brauchst-nix-wissen\\\/\",\"name\":\"Du brauchst nix wissen\u2026 - Was Sch\u00fcler lernen m\u00fcss(t)en - Thomas&#039; Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2021\\\/01\\\/07\\\/du-brauchst-nix-wissen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2021\\\/01\\\/07\\\/du-brauchst-nix-wissen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/thomas-2021-a.jpg\",\"datePublished\":\"2021-01-07T08:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#\\\/schema\\\/person\\\/7d7adc47b52b6c92021d3a5bce99592e\"},\"description\":\"\u2026\u00a0du musst nur wissen, wo's steht. Was mir mein HTL-Professor beigebracht hat und warum einer seiner Spr\u00fcche heute mehr gilt denn je.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2021\\\/01\\\/07\\\/du-brauchst-nix-wissen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2021\\\/01\\\/07\\\/du-brauchst-nix-wissen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2021\\\/01\\\/07\\\/du-brauchst-nix-wissen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/thomas-2021-a.jpg\",\"contentUrl\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/thomas-2021-a.jpg\",\"width\":1600,\"height\":1067,\"caption\":\"Thomas Sommeregger \u00a9 thecreatingclick\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2021\\\/01\\\/07\\\/du-brauchst-nix-wissen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learning\",\"item\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/category\\\/learning\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Du brauchst nix wissen\u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/\",\"name\":\"Thomas&#039; Blog\",\"description\":\"Meine Gedanken verpackt in Null und Eins, 100% pers\u00f6nlich\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#\\\/schema\\\/person\\\/7d7adc47b52b6c92021d3a5bce99592e\",\"name\":\"Thomas Sommeregger\",\"description\":\"Hallo, mein Name ist Thomas Sommeregger. Ich bin Betreiber sowie Haupt-Autor von Thomas' Blog. Meine Gedanken drehen sich hier recht breit um das Arbeits-, Familien- und Freizeitleben. Als Patchwork-Vater, Unternehmer und Hobby-Marathonl\u00e4ufer lebe ich in der Stadt Salzburg in \u00d6sterreich. Wenn dich Online Marketing, Unternehmertum, (Lauf-)Sport oder hin und wieder die eine oder andere Anekdote von mir interessieren, freue ich mich, wenn du mir weiter folgst.\",\"sameAs\":[\"https:\\\/\\\/www.digitalbuero.at\",\"https:\\\/\\\/www.facebook.com\\\/digitalbuero.at\",\"https:\\\/\\\/twitter.com\\\/tsommeregger\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thomassommeregger\",\"https:\\\/\\\/x.com\\\/tsommeregger\",\"https:\\\/\\\/soundcloud.com\\\/user-649426735\"],\"url\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/author\\\/thomas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Du brauchst nix wissen\u2026 - Was Sch\u00fcler lernen m\u00fcss(t)en - Thomas&#039; Blog","description":"\u2026\u00a0du musst nur wissen, wo's steht. Was mir mein HTL-Professor beigebracht hat und warum einer seiner Spr\u00fcche heute mehr gilt denn je.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/","og_locale":"de_DE","og_type":"article","og_title":"Du brauchst nix wissen\u2026 - Was Sch\u00fcler lernen m\u00fcss(t)en - Thomas&#039; Blog","og_description":"\u2026\u00a0du musst nur wissen, wo's steht. Was mir mein HTL-Professor beigebracht hat und warum einer seiner Spr\u00fcche heute mehr gilt denn je.","og_url":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/","og_site_name":"Thomas&#039; Blog","article_publisher":"https:\/\/www.facebook.com\/thomas.sommeregger","article_author":"https:\/\/www.facebook.com\/digitalbuero.at","article_published_time":"2021-01-07T08:00:00+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2021\/01\/thomas-2021-a.jpg","type":"image\/jpeg"}],"author":"Thomas Sommeregger","twitter_card":"summary_large_image","twitter_creator":"@tsommeregger","twitter_site":"@tsommeregger","twitter_misc":{"Verfasst von":"Thomas Sommeregger","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/#article","isPartOf":{"@id":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/"},"author":{"name":"Thomas Sommeregger","@id":"https:\/\/www.digitalbuero.at\/content\/#\/schema\/person\/7d7adc47b52b6c92021d3a5bce99592e"},"headline":"Du brauchst nix wissen\u2026","datePublished":"2021-01-07T08:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/"},"wordCount":1060,"commentCount":0,"image":{"@id":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2021\/01\/thomas-2021-a.jpg","keywords":["bildung","learning","life","lifelonglearning","Schule"],"articleSection":["Learning","Life"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/","url":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/","name":"Du brauchst nix wissen\u2026 - Was Sch\u00fcler lernen m\u00fcss(t)en - Thomas&#039; Blog","isPartOf":{"@id":"https:\/\/www.digitalbuero.at\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/#primaryimage"},"image":{"@id":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2021\/01\/thomas-2021-a.jpg","datePublished":"2021-01-07T08:00:00+00:00","author":{"@id":"https:\/\/www.digitalbuero.at\/content\/#\/schema\/person\/7d7adc47b52b6c92021d3a5bce99592e"},"description":"\u2026\u00a0du musst nur wissen, wo's steht. Was mir mein HTL-Professor beigebracht hat und warum einer seiner Spr\u00fcche heute mehr gilt denn je.","breadcrumb":{"@id":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/#primaryimage","url":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2021\/01\/thomas-2021-a.jpg","contentUrl":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2021\/01\/thomas-2021-a.jpg","width":1600,"height":1067,"caption":"Thomas Sommeregger \u00a9 thecreatingclick"},{"@type":"BreadcrumbList","@id":"https:\/\/www.digitalbuero.at\/content\/2021\/01\/07\/du-brauchst-nix-wissen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.digitalbuero.at\/content\/"},{"@type":"ListItem","position":2,"name":"Learning","item":"https:\/\/www.digitalbuero.at\/content\/category\/learning\/"},{"@type":"ListItem","position":3,"name":"Du brauchst nix wissen\u2026"}]},{"@type":"WebSite","@id":"https:\/\/www.digitalbuero.at\/content\/#website","url":"https:\/\/www.digitalbuero.at\/content\/","name":"Thomas&#039; Blog","description":"Meine Gedanken verpackt in Null und Eins, 100% pers\u00f6nlich","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.digitalbuero.at\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.digitalbuero.at\/content\/#\/schema\/person\/7d7adc47b52b6c92021d3a5bce99592e","name":"Thomas Sommeregger","description":"Hallo, mein Name ist Thomas Sommeregger. Ich bin Betreiber sowie Haupt-Autor von Thomas' Blog. Meine Gedanken drehen sich hier recht breit um das Arbeits-, Familien- und Freizeitleben. Als Patchwork-Vater, Unternehmer und Hobby-Marathonl\u00e4ufer lebe ich in der Stadt Salzburg in \u00d6sterreich. Wenn dich Online Marketing, Unternehmertum, (Lauf-)Sport oder hin und wieder die eine oder andere Anekdote von mir interessieren, freue ich mich, wenn du mir weiter folgst.","sameAs":["https:\/\/www.digitalbuero.at","https:\/\/www.facebook.com\/digitalbuero.at","https:\/\/twitter.com\/tsommeregger","https:\/\/www.linkedin.com\/in\/thomassommeregger","https:\/\/x.com\/tsommeregger","https:\/\/soundcloud.com\/user-649426735"],"url":"https:\/\/www.digitalbuero.at\/content\/author\/thomas\/"}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/posts\/1869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/comments?post=1869"}],"version-history":[{"count":0,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/posts\/1869\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/media\/1881"}],"wp:attachment":[{"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/media?parent=1869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/categories?post=1869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/tags?post=1869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}