{"id":1123,"date":"2020-10-03T09:00:40","date_gmt":"2020-10-03T07:00:40","guid":{"rendered":"https:\/\/www.digitalbuero.at\/content\/?p=1123"},"modified":"2020-10-04T06:50:00","modified_gmt":"2020-10-04T04:50:00","slug":"bulletproof-coffee","status":"publish","type":"post","link":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/","title":{"rendered":"Kaffee? Bitte Bulletproof!"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Espresso, Latte, Americano\u2026 Welches H\u00e4ferl h\u00e4tten&#8217;s denn gern? Und welche Zubereitungsart? Welche Bohnen? Welche R\u00f6stung? Welchen Mahlgrad? AAAAAhhhh, STOP! Geht&#8217;s dir nicht \u00e4hnlich, zu Hause, im B\u00fcro oder im Kaffeehaus? <strong>Ich trinke liebend gerne Kaffee<\/strong> und gebe dir hier einen kurzen Einblick warum es mir die Zubereitungsart <strong>Bulletproof Coffee <\/strong>besonders angetan hat.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p><strong>Verl\u00e4ngert, mit Milch und 2-3 Teel\u00f6ffel Zucker.<\/strong> Puh, ich kann es heute gar nicht mehr glauben, aber diese mittelm\u00e4\u00dfig gesunde Kombination war mehr als ein Jahrzehnt der Kaffee meiner Wahl, mehrmals pro Tag wohlgemerkt. Erst langsam habe ich mir den Zucker abgew\u00f6hnt, seit kurzer Zeit auch die Milch. Ein kurzer <strong>Espresso<\/strong> oder <strong>Americano<\/strong> ist heute meist meine erste Wahl ausw\u00e4rts in Caf\u00e9s. Schnell, schwarz, k\u00f6stlich.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Dann gab ich Milch in den Kaffee und dieser wurde depressiv, weil ich ihn nicht so akzeptiert habe, wie er ist.<\/p><cite>Frei nach Josef Hader (Privat)<\/cite><\/blockquote><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>In der Fr\u00fch nehme ich mir zu Hause aber etwas mehr Zeit f\u00fcr meinen <strong>Bulletproof Coffee<\/strong>. Was hat&#8217;s damit auf sich und warum ich ihn trinke?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vom Zuckerkaffee zum Butterkaffee<\/h2>\n\n\n\n<p>Warum nennt man einen Kaffee &#8222;kugelsicher&#8220;? Wie kommt man darauf, <strong>Butter in den Kaffee<\/strong> zu tun? Wie mixt man einen Bulletproof Coffee schlie\u00dflich zusammen? Ich beschreibe dir kurz, wie ich drauf gekommen bin und wie ich meinen morgendlichen Kaffee zubereite.<\/p>\n\n\n\n<p>&#8222;Erfunden&#8220; hat diese ganz spezielle Art Kaffee zuzubereiten der Amerikaner <a href=\"https:\/\/blog.daveasprey.com\/about-dave-asprey\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dave Asprey<\/a>. Mittlerweile hat er als Unternehmer und Autor eine ganze <a href=\"https:\/\/www.bulletproof.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bulletproof<\/a>-Welt aufgebaut, um seinen &#8222;Biohacking&#8220;-Lifestyle rund um B\u00fccher, Podcasts, Rezepte und Produkte mit anderen zu teilen. Wer einmal in Santa Monica in Kalifornien ist, kann auch das Bulletproof Coffee <a href=\"https:\/\/goo.gl\/maps\/csxDMLiS4wGKvMTd7\" target=\"_blank\" rel=\"noreferrer noopener\">pers\u00f6nlich besuchen<\/a>. Auch einen Blick in sein <strong>Buch<\/strong> &#8222;The Bulletproof Diet&#8220; kann ich hier kurz empfehlen.<\/p>\n\n\n\n <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PGlmcmFtZSBzdHlsZT0id2lkdGg6MTIwcHg7aGVpZ2h0OjI0MHB4OyIgbWFyZ2lud2lkdGg9IjAiIG1hcmdpbmhlaWdodD0iMCIgc2Nyb2xsaW5nPSJubyIgZnJhbWVib3JkZXI9IjAiIHNyYz0iLy93cy1ldS5hbWF6b24tYWRzeXN0ZW0uY29tL3dpZGdldHMvcT9TZXJ2aWNlVmVyc2lvbj0yMDA3MDgyMiZhbXA7T25lSlM9MSZhbXA7T3BlcmF0aW9uPUdldEFkSHRtbCZhbXA7TWFya2V0UGxhY2U9REUmYW1wO3NvdXJjZT1zcyZhbXA7cmVmPWFzX3NzX2xpX3RpbCZhbXA7YWRfdHlwZT1wcm9kdWN0X2xpbmsmYW1wO3RyYWNraW5nX2lkPWRpZ2l0YWxidWVyb2EtMjEmYW1wO2xhbmd1YWdlPWRlX0RFJmFtcDttYXJrZXRwbGFjZT1hbWF6b24mYW1wO3JlZ2lvbj1ERSZhbXA7cGxhY2VtZW50PUIwMEs4RFNUV1UmYW1wO2FzaW5zPUIwMEs4RFNUV1UmYW1wO2xpbmtJZD0zZDg3YzdkZDUyNjc2MzBhOWYyY2UwZGU0MWJmZjk1YiZhbXA7c2hvd19ib3JkZXI9dHJ1ZSZhbXA7bGlua19vcGVuc19pbl9uZXdfd2luZG93PXRydWUiPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Standard<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Die Theorie<\/h3>\n\n\n\n<p>Grunds\u00e4tzlich geht es bei der Idee darum, dem K\u00f6rper am Morgen nicht Kohlehydrate sondern Fett zu verabreichen. Asprey hat sich das in Nepal <strong>von Sherpas abgeschaut<\/strong>, die einen L\u00f6ffel Yakbutter in ihren Tee geben, um <strong>mehr Energie f\u00fcr ihre Anstrengungen<\/strong> zu haben. Wieder zu Hause hat er Tee mit Kaffee getauscht, einen klingenden Namen ausgedacht, et voil\u00e0, fertig war die Gesch\u00e4ftsidee.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Was kommt in den Bulletproof Coffee?<\/h2>\n\n\n\n<p>Nun aber genug der Theorie, hier die &#8222;hard facts&#8220;, was ich <strong>in meinen Bulletproof Coffee<\/strong> gebe:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ca. 30 g frisch gemahlenen Kaffee<\/li><li>Ca. 500 ml hei\u00dfes Wasser<\/li><li>Zubereitet in der Chemex als Filterkaffee (siehe Foto) oder mit der French Press<\/li><li>Vom fertigen Kaffee nehme ich dann eine Tasse mit ca. 300 ml (die verbleibende Kaffeemenge bekommt meist meine Partnerin <a rel=\"noreferrer noopener\" href=\"https:\/\/www.oliviaulbing.com\/\" target=\"_blank\">Olivia<\/a> &lt;3) und gebe die folgenden Zutaten hinein:<\/li><li>1-2 Essl\u00f6ffel <strong>Weidebutter<\/strong><\/li><li>1 Essl\u00f6ffel <strong>MCT-\u00d6l<\/strong> (C8)<\/li><li>Optional: Einen Essl\u00f6ffel Collagenpulver<\/li><li>Optional: Etwas Vanillepulver (nach Geschmack, manchmal auch Zimt)<\/li><\/ul>\n\n\n\n<p><strong>Wichtiger Hinweis:<\/strong> Die Zutaten solltest du dann <strong>unbedingt<\/strong> mit einem <strong>Stabmixer<\/strong> durchmischen, um einen schaumigen Kaffee wie in meinem Titelbild dargestellt zu bekommen.<\/p>\n\n\n\n<p>Ich habe den <strong>Anf\u00e4ngerfehler<\/strong> gemacht, bei den ersten Versuchen einfach nur umzur\u00fchren. Das sieht dann einfach nur grauslich aus, weil Butter bzw. \u00d6l als &#8222;Fettaugen&#8220; im schwarzen Kaffee umher schwimmen. Machst du es richtig, bekommst du eine hellbraune Mischung, die zwar wie Milchkaffee aussieht, aber nat\u00fcrlich anders schmeckt. Am Beginn &#8222;gew\u00f6hnungsbed\u00fcrftig&#8220;, mittlerweile mag ich den Geschmack genauso wie die Wirkung.<\/p>\n\n\n\n<p>Im Bild siehst du, wie dieses morgendliche &#8222;Projekt&#8220; bei mir zu Hause aussieht. Wenn du magst, klicke auch gerne weiter zum <a href=\"https:\/\/www.bulletproof.com\/recipes\/bulletproof-diet-recipes\/bulletproof-coffee-recipe\/\" target=\"_blank\" rel=\"noreferrer noopener\">Originalrezept<\/a>, vor allem um auch die <strong>Begr\u00fcndung und Wirkung der einzelnen Zutaten<\/strong> nachzulesen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/bulletproof-coffee-mischen-t-1024x768.jpg\" alt=\"Bulletproof Coffee mischen und zubereiten\" class=\"wp-image-1128\" srcset=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/bulletproof-coffee-mischen-t-1024x768.jpg 1024w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/bulletproof-coffee-mischen-t-300x225.jpg 300w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/bulletproof-coffee-mischen-t-768x576.jpg 768w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/bulletproof-coffee-mischen-t-1536x1152.jpg 1536w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/bulletproof-coffee-mischen-t-1200x900.jpg 1200w, https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/bulletproof-coffee-mischen-t.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Du willst Bulletproof Coffee mischen und selbst zubereiten? Das erfordert ein paar Zutaten und auch ein wenig mehr Zeit, als schnell auf eine Taste zu dr\u00fccken.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Und was bringt&#8217;s?<\/h2>\n\n\n\n<p>Mir pers\u00f6nlich bringt es etwas <strong>Abwechslung<\/strong> in den bisherigen Fr\u00fchst\u00fccksalltag und genug <strong>Energie<\/strong> f\u00fcr einen kraftvollen Vormittag, ohne etwas zu essen. Es ist nicht gelogen, dass ich nach einem Bulletproof Coffee am Morgen erst ab ca. 13-14 Uhr hungrig bin. Im Vergleich knurrt der Magen nach schnellen 1-2 St\u00fcck (Toast-)Brot und einem Espresso bereits wieder ab 10-11 Uhr. <\/p>\n\n\n\n<p>Wie bevorzugst du deinen Kaffee und hast du schon einmal &#8222;kugelsicheren&#8220; Kaffee getrunken? Schreib mir gerne deine Vorlieben in die Kommentare! <\/p>\n\n\n\n<p>So, jetzt brauche ich aber einen Kaffee! ;) <\/p>\n\n\n\n<p>Alles Liebe,<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"112\" src=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/signature-thomas-kl-t.jpg\" alt=\"Signature Thomas\" class=\"wp-image-1115\"\/><\/figure>\n\n\n\n<p>PS: Falls du noch mehr herausfinden m\u00f6chtest, empfehle ich dir gerne die folgenden Links, von denen ich mein Wissen und\/oder die Produkte aus diesem Artikel beziehe (<em>pers\u00f6nliche Empfehlung, keine bezahlten Kooperationen oder Werbeeinschaltungen<\/em>):<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.coffeecircle.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">Coffee Circle<\/a> \u2013&nbsp;Die perfekte Anlaufstelle f\u00fcr Produkte und Zubeh\u00f6r (zB Chemex, Filter, Kaffeem\u00fchle)<\/li><li><a href=\"https:\/\/www.primal-state.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Primal State<\/a> \u2013&nbsp;Hier kaufe ich meistens das MCT-\u00d6l sowie das Collagen (zuletzt auch Vitamin D3 Tropfen, die sich auch gut noch in den Kaffee geben lassen)<\/li><li><a href=\"https:\/\/library-coffee-roastery.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">Library Coffee<\/a> \u2013&nbsp;Diese \u00f6sterreichische R\u00f6sterei liefert mir derzeit die passenden Kaffeebohnen f\u00fcr meinen Bulletproof Coffee<\/li><\/ul>\n\n\n\n<p>Die anderen Artikel zu meinem <a href=\"\/content\/category\/blogtober\/\">Blogtober<\/a>-Projekt hast du schon gelesen?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Espresso, Latte, Americano\u2026 Welches H\u00e4ferl h\u00e4tten&#8217;s denn gern? Und welche Zubereitungsart? Welche Bohnen? Welche R\u00f6stung? Welchen Mahlgrad? AAAAAhhhh, STOP! Geht&#8217;s dir nicht \u00e4hnlich, zu Hause, im B\u00fcro oder im Kaffeehaus? Ich trinke liebend gerne Kaffee und gebe dir hier einen kurzen Einblick warum es mir die Zubereitungsart Bulletproof Coffee besonders angetan hat.<\/p>\n","protected":false},"author":2,"featured_media":1127,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[381],"tags":[382,385,384,386,383],"class_list":["post-1123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogtober","tag-blogtober","tag-bulletproof","tag-bulletproof-coffee","tag-coffee","tag-kaffee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kaffee? Bitte Bulletproof! Rezept und pers\u00f6nliche Tipps - Thomas&#039; Blog<\/title>\n<meta name=\"description\" content=\"Was hat es mit Bulletproof Coffee auf sich, von dem pl\u00f6tzlich so viele reden? Welche Zutaten braucht&#039;s und worauf musst du achten? Lies hier\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kaffee? Bitte Bulletproof! Rezept und pers\u00f6nliche Tipps - Thomas&#039; Blog\" \/>\n<meta property=\"og:description\" content=\"Was hat es mit Bulletproof Coffee auf sich, von dem pl\u00f6tzlich so viele reden? Welche Zutaten braucht&#039;s und worauf musst du achten? Lies hier\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/\" \/>\n<meta property=\"og:site_name\" content=\"Thomas&#039; Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/thomas.sommeregger\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/digitalbuero.at\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-03T07:00:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-04T04:50:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/bulletproof-coffee-t.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thomas Sommeregger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tsommeregger\" \/>\n<meta name=\"twitter:site\" content=\"@tsommeregger\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Sommeregger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2020\\\/10\\\/03\\\/bulletproof-coffee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2020\\\/10\\\/03\\\/bulletproof-coffee\\\/\"},\"author\":{\"name\":\"Thomas Sommeregger\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#\\\/schema\\\/person\\\/7d7adc47b52b6c92021d3a5bce99592e\"},\"headline\":\"Kaffee? Bitte Bulletproof!\",\"datePublished\":\"2020-10-03T07:00:40+00:00\",\"dateModified\":\"2020-10-04T04:50:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2020\\\/10\\\/03\\\/bulletproof-coffee\\\/\"},\"wordCount\":820,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2020\\\/10\\\/03\\\/bulletproof-coffee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/bulletproof-coffee-t.jpg\",\"keywords\":[\"blogtober\",\"bulletproof\",\"bulletproof-coffee\",\"coffee\",\"kaffee\"],\"articleSection\":[\"Blogtober\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2020\\\/10\\\/03\\\/bulletproof-coffee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2020\\\/10\\\/03\\\/bulletproof-coffee\\\/\",\"url\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2020\\\/10\\\/03\\\/bulletproof-coffee\\\/\",\"name\":\"Kaffee? Bitte Bulletproof! Rezept und pers\u00f6nliche Tipps - Thomas&#039; Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2020\\\/10\\\/03\\\/bulletproof-coffee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2020\\\/10\\\/03\\\/bulletproof-coffee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/bulletproof-coffee-t.jpg\",\"datePublished\":\"2020-10-03T07:00:40+00:00\",\"dateModified\":\"2020-10-04T04:50:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#\\\/schema\\\/person\\\/7d7adc47b52b6c92021d3a5bce99592e\"},\"description\":\"Was hat es mit Bulletproof Coffee auf sich, von dem pl\u00f6tzlich so viele reden? Welche Zutaten braucht's und worauf musst du achten? Lies hier\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2020\\\/10\\\/03\\\/bulletproof-coffee\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2020\\\/10\\\/03\\\/bulletproof-coffee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2020\\\/10\\\/03\\\/bulletproof-coffee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/bulletproof-coffee-t.jpg\",\"contentUrl\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/bulletproof-coffee-t.jpg\",\"width\":1920,\"height\":1440,\"caption\":\"Bulletproof Coffee (Foto: Thomas Sommeregger)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/2020\\\/10\\\/03\\\/bulletproof-coffee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blogtober\",\"item\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/category\\\/blogtober\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kaffee? Bitte Bulletproof!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/\",\"name\":\"Thomas&#039; Blog\",\"description\":\"Meine Gedanken verpackt in Null und Eins, 100% pers\u00f6nlich\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/#\\\/schema\\\/person\\\/7d7adc47b52b6c92021d3a5bce99592e\",\"name\":\"Thomas Sommeregger\",\"description\":\"Hallo, mein Name ist Thomas Sommeregger. Ich bin Betreiber sowie Haupt-Autor von Thomas' Blog. Meine Gedanken drehen sich hier recht breit um das Arbeits-, Familien- und Freizeitleben. Als Patchwork-Vater, Unternehmer und Hobby-Marathonl\u00e4ufer lebe ich in der Stadt Salzburg in \u00d6sterreich. Wenn dich Online Marketing, Unternehmertum, (Lauf-)Sport oder hin und wieder die eine oder andere Anekdote von mir interessieren, freue ich mich, wenn du mir weiter folgst.\",\"sameAs\":[\"https:\\\/\\\/www.digitalbuero.at\",\"https:\\\/\\\/www.facebook.com\\\/digitalbuero.at\",\"https:\\\/\\\/twitter.com\\\/tsommeregger\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thomassommeregger\",\"https:\\\/\\\/x.com\\\/tsommeregger\",\"https:\\\/\\\/soundcloud.com\\\/user-649426735\"],\"url\":\"https:\\\/\\\/www.digitalbuero.at\\\/content\\\/author\\\/thomas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kaffee? Bitte Bulletproof! Rezept und pers\u00f6nliche Tipps - Thomas&#039; Blog","description":"Was hat es mit Bulletproof Coffee auf sich, von dem pl\u00f6tzlich so viele reden? Welche Zutaten braucht's und worauf musst du achten? Lies hier","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/","og_locale":"de_DE","og_type":"article","og_title":"Kaffee? Bitte Bulletproof! Rezept und pers\u00f6nliche Tipps - Thomas&#039; Blog","og_description":"Was hat es mit Bulletproof Coffee auf sich, von dem pl\u00f6tzlich so viele reden? Welche Zutaten braucht's und worauf musst du achten? Lies hier","og_url":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/","og_site_name":"Thomas&#039; Blog","article_publisher":"https:\/\/www.facebook.com\/thomas.sommeregger","article_author":"https:\/\/www.facebook.com\/digitalbuero.at","article_published_time":"2020-10-03T07:00:40+00:00","article_modified_time":"2020-10-04T04:50:00+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/bulletproof-coffee-t.jpg","type":"image\/jpeg"}],"author":"Thomas Sommeregger","twitter_card":"summary_large_image","twitter_creator":"@tsommeregger","twitter_site":"@tsommeregger","twitter_misc":{"Verfasst von":"Thomas Sommeregger","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/#article","isPartOf":{"@id":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/"},"author":{"name":"Thomas Sommeregger","@id":"https:\/\/www.digitalbuero.at\/content\/#\/schema\/person\/7d7adc47b52b6c92021d3a5bce99592e"},"headline":"Kaffee? Bitte Bulletproof!","datePublished":"2020-10-03T07:00:40+00:00","dateModified":"2020-10-04T04:50:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/"},"wordCount":820,"commentCount":1,"image":{"@id":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/bulletproof-coffee-t.jpg","keywords":["blogtober","bulletproof","bulletproof-coffee","coffee","kaffee"],"articleSection":["Blogtober"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/","url":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/","name":"Kaffee? Bitte Bulletproof! Rezept und pers\u00f6nliche Tipps - Thomas&#039; Blog","isPartOf":{"@id":"https:\/\/www.digitalbuero.at\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/#primaryimage"},"image":{"@id":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/bulletproof-coffee-t.jpg","datePublished":"2020-10-03T07:00:40+00:00","dateModified":"2020-10-04T04:50:00+00:00","author":{"@id":"https:\/\/www.digitalbuero.at\/content\/#\/schema\/person\/7d7adc47b52b6c92021d3a5bce99592e"},"description":"Was hat es mit Bulletproof Coffee auf sich, von dem pl\u00f6tzlich so viele reden? Welche Zutaten braucht's und worauf musst du achten? Lies hier","breadcrumb":{"@id":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/#primaryimage","url":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/bulletproof-coffee-t.jpg","contentUrl":"https:\/\/www.digitalbuero.at\/content\/wp-content\/uploads\/2020\/10\/bulletproof-coffee-t.jpg","width":1920,"height":1440,"caption":"Bulletproof Coffee (Foto: Thomas Sommeregger)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.digitalbuero.at\/content\/2020\/10\/03\/bulletproof-coffee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.digitalbuero.at\/content\/"},{"@type":"ListItem","position":2,"name":"Blogtober","item":"https:\/\/www.digitalbuero.at\/content\/category\/blogtober\/"},{"@type":"ListItem","position":3,"name":"Kaffee? Bitte Bulletproof!"}]},{"@type":"WebSite","@id":"https:\/\/www.digitalbuero.at\/content\/#website","url":"https:\/\/www.digitalbuero.at\/content\/","name":"Thomas&#039; Blog","description":"Meine Gedanken verpackt in Null und Eins, 100% pers\u00f6nlich","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.digitalbuero.at\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.digitalbuero.at\/content\/#\/schema\/person\/7d7adc47b52b6c92021d3a5bce99592e","name":"Thomas Sommeregger","description":"Hallo, mein Name ist Thomas Sommeregger. Ich bin Betreiber sowie Haupt-Autor von Thomas' Blog. Meine Gedanken drehen sich hier recht breit um das Arbeits-, Familien- und Freizeitleben. Als Patchwork-Vater, Unternehmer und Hobby-Marathonl\u00e4ufer lebe ich in der Stadt Salzburg in \u00d6sterreich. Wenn dich Online Marketing, Unternehmertum, (Lauf-)Sport oder hin und wieder die eine oder andere Anekdote von mir interessieren, freue ich mich, wenn du mir weiter folgst.","sameAs":["https:\/\/www.digitalbuero.at","https:\/\/www.facebook.com\/digitalbuero.at","https:\/\/twitter.com\/tsommeregger","https:\/\/www.linkedin.com\/in\/thomassommeregger","https:\/\/x.com\/tsommeregger","https:\/\/soundcloud.com\/user-649426735"],"url":"https:\/\/www.digitalbuero.at\/content\/author\/thomas\/"}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/posts\/1123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/comments?post=1123"}],"version-history":[{"count":0,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/posts\/1123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/media\/1127"}],"wp:attachment":[{"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/media?parent=1123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/categories?post=1123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.digitalbuero.at\/content\/wp-json\/wp\/v2\/tags?post=1123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}